{"id":6525,"date":"2025-10-06T16:24:43","date_gmt":"2025-10-06T14:24:43","guid":{"rendered":"http:\/\/sendersfinancers.com\/?page_id=6525"},"modified":"2026-02-26T10:57:40","modified_gmt":"2026-02-26T08:57:40","slug":"guarderias","status":"publish","type":"page","link":"https:\/\/www.sendersfinancers.com\/es\/ayuntamientos\/estudios-de-estructura-de-gastos\/guarderias\/","title":{"rendered":"Guarder\u00edas"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(0,0,0,0)\u00bb saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_slider _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bbCatamaran||||||||\u00bb body_text_align=\u00bbleft\u00bb body_text_color=\u00bb#000000&#8243; body_font_size=\u00bb18px\u00bb background_color=\u00bbRGBA(0,0,0,0)\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb18px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#565141&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bbRGBA(0,0,0,0)\u00bb button_border_radius=\u00bb0px\u00bb button_font=\u00bbCatamaran||||||||\u00bb button_use_icon=\u00bboff\u00bb text_orientation=\u00bbleft\u00bb min_height=\u00bb449.3px\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_slide button_link=\u00bb\/contacto\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh1&#8243; header_font=\u00bbCatamaran|900|||||||\u00bb header_text_align=\u00bbleft\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_font_size=\u00bb60px\u00bb body_text_color=\u00bb#FFFFFF\u00bb background_color=\u00bbRGBA(0,0,0,0)\u00bb background_enable_color=\u00bbon\u00bb background_image=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2025\/10\/Banner-PAGE-2.png\u00bb background_enable_image=\u00bbon\u00bb header_font_size_tablet=\u00bb\u00bb header_font_size_phone=\u00bb30px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb body_text_shadow_style=\u00bbpreset5&#8243; global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<h1 class=\"et_pb_slide_title\">GUARDER\u00cdAS<\/h1>\n<p>[\/et_pb_slide][\/et_pb_fullwidth_slider][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; custom_margin=\u00bb60px||||false|false\u00bb custom_padding=\u00bb10px||10px||false|false\u00bb border_width_top=\u00bb8px\u00bb border_color_top=\u00bb#569033&#8243; collapsed=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbCatamaran|900|||||||\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#569033&#8243; header_2_font_size=\u00bb16px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>SERVICIO DE ESTUDIOS DE ESTRUCTURA DE COSTES DE GUARDER\u00cdAS<\/h1>\n<h2 style=\"text-align: center;\">SERVICIOS DE CONSULTOR\u00cdA FINANCIERA PARA AYUNTAMIENTOS<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb40px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2025\/10\/Banner-PETIT-Servicio-1.png\u00bb title_text=\u00bbBanner PETIT Servicio (1)\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong>La Ley 5\/2004, de 9 de julio, de creaci\u00f3n de guarder\u00edas de calidad, estableci\u00f3 que el Gobierno de Catalu\u00f1a deb\u00eda garantizar el car\u00e1cter educativo, la calidad y los requisitos m\u00ednimos que deben cumplir las guarder\u00edas que la realidad catalana exige<\/strong>, y que debe considerarlas como una parte del sistema educativo; asimismo, deb\u00eda garantizar que al final del per\u00edodo 2004-2008 la red de guarder\u00edas de titularidad p\u00fablica de Catalu\u00f1a incluyera un m\u00ednimo de 30.000 plazas de nueva creaci\u00f3n y que \u00e9stas se mantuvieran en el futuro.<br \/>Adicionalmente, <strong>en el \u00e1mbito de las guarder\u00edas, es de relevancia el DECRETO 282\/2006, de 4 de julio, por el que se regulan el primer ciclo de la educaci\u00f3n infantil y los requisitos de los centros<\/strong>. Por lo que respecta al \u00e1mbito de aplicaci\u00f3n, es de aplicaci\u00f3n a los centros que imparten el primer ciclo de la educaci\u00f3n infantil.<\/p>\n<p>Estos centros acogen de forma regular, es decir, continuada y sistem\u00e1tica, a ni\u00f1os de cero a tres a\u00f1os, y les dan servicio educativo seg\u00fan las condiciones y requisitos que se establecen en este Decreto.<strong> Para su funcionamiento, debe crearlos o autorizarlos la Administraci\u00f3n educativa.<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Este Decreto establece los requisitos m\u00ednimos en cuanto al n\u00famero y calificaci\u00f3n de los profesionales, de los espacios y de las instalaciones donde se produce la acci\u00f3n educativa, el n\u00famero m\u00e1ximo de ni\u00f1os por unidad, el procedimiento de autorizaci\u00f3n administrativa de estos centros y la participaci\u00f3n de la comunidad educativa, as\u00ed como la posibilidad de delegar determinadas competencias en los ayuntamientos.<\/p>\n<p>El impacto y relevancia de las guarder\u00edas en el contexto de la Administraci\u00f3n Local es muy significativa as\u00ed como tambi\u00e9n la necesidad de \u00e9stas, de <strong>contar con estudios econ\u00f3micos de costes bien fundamentados que determinen y soporten el Presupuesto Base de Licitaci\u00f3n<\/strong> (en adelante \u201cVEC\u201d) <strong>as\u00ed como el Valor Estimado del Contrato<\/strong> aspectos significativos del contrato como la duraci\u00f3n del mismo, la tipolog\u00eda de contrato (contrato de servicios o concesi\u00f3n de servicios), <strong>el agente que asume las inversiones y en qu\u00e9 condiciones <\/strong>(Ayuntamiento o gestor del servicio)<strong> o bien cu\u00e1l es el \u201cmix\u201d de financiaci\u00f3n \u00f3ptima del servicio <\/strong> de aportaci\u00f3n del Ayuntamiento).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb40px||20px||false|false\u00bb custom_padding=\u00bb10px||0px||false|false\u00bb border_width_top=\u00bb8px\u00bb border_color_top=\u00bb#569033&#8243; collapsed=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbCatamaran|900|||||||\u00bb header_text_color=\u00bb#569033&#8243; header_2_font=\u00bbCatamaran|900|||||||\u00bb header_2_text_color=\u00bb#569033&#8243; header_2_font_size=\u00bb30px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: center;\">OBJETIVOS Y BENEFICIOS<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb40px|20%|60px|20%|false|false\u00bb custom_padding=\u00bb||||false|false\u00bb box_shadow_style=\u00bbpreset1&#8243; collapsed=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran|900|||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb20px\u00bb background_color=\u00bb#569033&#8243; text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb5px||5px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>OBJETIVOS<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_5,1_5,1_5,1_5,1_5&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb1&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb border_color_all=\u00bb#d8d8d8&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|20px|20px|false|false\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d8d8d8&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\">Identificaci\u00f3n y determinaci\u00f3n del PBL as\u00ed como VEC<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|20px|20px|false|false\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d8d8d8&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\">Establecer una duraci\u00f3n coherente y fundamentada del contrato<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|20px|20px|false|false\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d8d8d8&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\">Establecer una estructura de financiaci\u00f3n del servicio equilibrada entre los distintos agentes financiadores<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|20px|20px|false|false\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d8d8d8&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\">Identificar del coste objetivo por tipo de prestaci\u00f3n (escolaridad, comedor, acogida), aula y alumno<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|20px|20px|false|false\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d8d8d8&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\">Adecuado traslado de las condiciones del Convenio Colectivo al personal del servicio<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb20px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran|900|||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb20px\u00bb background_color=\u00bb#569033&#8243; text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb5px||5px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>BENEFICIOS<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_5,1_5,1_5,1_5,1_5&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb1&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb border_color_all=\u00bb#d8d8d8&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|20px|20px|false|false\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d8d8d8&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\">Equilibrio econ\u00f3mico y sostenibilidad financiera del servicio durante el per\u00edodo contractual<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|20px|20px|false|false\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d8d8d8&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\">Garantizar una retribuci\u00f3n al operador del servicio razonable y en coherencia con la rentabilidad del sector<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|20px|20px|false|false\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d8d8d8&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\">Comprensi\u00f3n y entendimiento de los principales aspectos de relevancia de la licitaci\u00f3n.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|20px|20px|false|false\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d8d8d8&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\">Propuesta de costes elaborada con criterios t\u00e9cnicos y en base a la realidad objetiva del servicio a licitar<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|20px|20px|false|false\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d8d8d8&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\">Establecimiento y determinaci\u00f3n de una pol\u00edtica tarifaria coherente<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb border_width_top=\u00bb8px\u00bb border_color_top=\u00bb#569033&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb min_height=\u00bb374.2px\u00bb custom_margin=\u00bb|auto|-28px|auto||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2025\/10\/Banner-PETIT-Servicio-2.png\u00bb title_text=\u00bbBanner PETIT Servicio (2)\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbCatamaran|900|||||||\u00bb header_text_color=\u00bb#569033&#8243; header_2_font=\u00bbCatamaran|900|||||||\u00bb header_2_text_color=\u00bb#569033&#8243; header_2_font_size=\u00bb30px\u00bb width=\u00bb100%\u00bb min_height=\u00bb74.8px\u00bb custom_margin=\u00bb|-61px|34px|||\u00bb custom_padding=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>SERVICIO DE ESTUDIOS DE<br \/>\nESTRUCTURA DE COSTES<br \/>\nDE GUARDER\u00cdAS<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; min_height=\u00bb173.2px\u00bb custom_margin=\u00bb-37px|||||\u00bb custom_padding=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Desde Senders Financers, preparamos estudios econ\u00f3micos que tienen por objetivos, <strong>i) la determinaci\u00f3n del coste objetivo del servicio de las guarder\u00edas municipales<\/strong> as\u00ed como determinar mecanismos de reparto que permitan identificar el coste del servicio por actividad y aula entre otros as\u00ed como<strong> ii) identificar el precio p\u00fablico a aplicar al usuario del servicio<\/strong> y as\u00ed intervenir en los mismos procedimientos:<\/p>\n<ol>\n<li>Identificaci\u00f3n y an\u00e1lisis de los costes del servicio por tipolog\u00eda de gasto as\u00ed como diferenciaci\u00f3n entre costes directos\/indirectos y entre costes del Ayuntamiento o del gestor del servicio entre otros.<\/li>\n<li>Asignaci\u00f3n y reparto de costes entre actividades (acogida, comedor, matr\u00edcula, material y escolaridad) y centros de coste (aula, alumnos).<\/li>\n<li>Determinaci\u00f3n del coste del servicio a pujar.<\/li>\n<li>Identificaci\u00f3n y an\u00e1lisis de los ingresos del servicio por tipolog\u00eda de ingreso (acogida, matr\u00edcula, material, comedor y escolaridad as\u00ed como bonificaciones que apliquen).<\/li>\n<li>Determinaci\u00f3n del precio p\u00fablico a aplicar al usuario y propuesta de financiaci\u00f3n de los distintos servicios.<\/li>\n<li>Indicadores de la Guarder\u00eda y comparativa con otros centros (C\u00edrculos de Comparaci\u00f3n Intermunicipales).<\/li>\n<li>Evaluaci\u00f3n de aspectos cualitativos relativos al marco contractual (oferta econ\u00f3mica, Pliegos, Reglamento, OOFF, Convenio Laboral de Aplicaci\u00f3n, Contrato entre otros).<\/li>\n<\/ol>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; min_height=\u00bb107px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Las licitaciones del servicio de guarder\u00edas municipales han presentado, en los \u00faltimos a\u00f1os, niveles de impugnaci\u00f3n y complejidad crecientes. Es por este motivo, <strong>que se hace necesario comprender los diferentes \u00e1mbitos que presentan incidencia en la contrataci\u00f3n p\u00fablica<\/strong> (fiscales, econ\u00f3micos, laborales, jur\u00eddicos, entre otros) as\u00ed como el entendimiento de los principales par\u00e1metros de relevancia del servicio (duraci\u00f3n contractual, aplicaci\u00f3n del Convenio Colectivo, tipolog\u00eda de contrato a aplicar, tratamiento de las inversiones, tratamiento de las inversiones, Industrial a aplicar, entre otros).<\/p>\n<p><strong>Desde Senders Financers contamos con amplia experiencia en la preparaci\u00f3n de informes econ\u00f3micos que tienen por finalidad la determinaci\u00f3n del coste objetivo del servicio de guarder\u00edas municipales<\/strong> y que sirven a los Ayuntamientos, para determinar el PBL y VEC de los servicios objeto de contrataci\u00f3n p\u00fablica. Por todo ello, ponemos a disposici\u00f3n de los Servicios T\u00e9cnicos municipales nuestro conocimiento para proporcionar asistencia t\u00e9cnica sobre estudios econ\u00f3micos de los costes de los diferentes servicios de guarder\u00edas municipales objeto de contrataci\u00f3n p\u00fablica.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb60px||40px||false|false\u00bb custom_padding=\u00bb10px||10px||false|false\u00bb border_width_top=\u00bb8px\u00bb border_color_top=\u00bb#569033&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbCatamaran|900|||||||\u00bb header_text_color=\u00bb#569033&#8243; header_2_font=\u00bbCatamaran|800|||||||\u00bb header_2_text_color=\u00bb#569033&#8243; header_2_font_size=\u00bb30px\u00bb custom_margin=\u00bb30px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: center;\"><strong>SOLVENCIA T\u00c9CNICA DE NUESTROS PROFESIONALES<\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb custom_margin=\u00bb20px||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb header_2_font=\u00bbCatamaran||||||||\u00bb header_3_font=\u00bbCatamaran|900|||||||\u00bb min_height=\u00bb400px\u00bb height=\u00bb400px\u00bb custom_padding=\u00bb20px|20px|20px|20px|false|false\u00bb box_shadow_style=\u00bbpreset1&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sendersfinancers.com\/wp-content\/uploads\/2024\/06\/figueres-300x105.png\" width=\"300\" height=\"105\" alt=\"\" class=\"wp-image-6104 alignnone size-medium\" style=\"display: block; margin-left: auto; margin-right: auto;\" srcset=\"https:\/\/www.sendersfinancers.com\/wp-content\/uploads\/2024\/06\/figueres-300x105.png 300w, https:\/\/www.sendersfinancers.com\/wp-content\/uploads\/2024\/06\/figueres.png 380w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\">AYUNTAMIENTO DE<\/h2>\n<h3 style=\"text-align: center;\">FIGUERES<\/h3>\n<div style=\"background: #f2f2f2; padding: 10px; margin: 10px 10px; text-align: center;\">Informe econ\u00f3mico de determinaci\u00f3n del coste objetivo del servicio de guarder\u00edas (2 escuelas) as\u00ed como del mix de financiaci\u00f3n \u00f3ptimo.<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb header_2_font=\u00bbCatamaran||||||||\u00bb header_3_font=\u00bbCatamaran|900|||||||\u00bb min_height=\u00bb400px\u00bb custom_margin=\u00bb||-4px|||\u00bb custom_padding=\u00bb20px|20px|0px|20px|false|false\u00bb box_shadow_style=\u00bbpreset1&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sendersfinancers.com\/wp-content\/uploads\/2022\/04\/1.-300x188.jpg\" width=\"222\" height=\"139\" alt=\"\" class=\"wp-image-5006 alignnone size-medium\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>\n<h2 style=\"text-align: center;\">AYUNTAMIENTO\u00a0DE<\/h2>\n<h3 style=\"text-align: center;\">MONTCADA I REIXAC<\/h3>\n<div style=\"background: #f2f2f2; padding: 10px; margin: 10px 10px; text-align: center;\">Informe econ\u00f3mico de determinaci\u00f3n del coste objetivo del servicio de guarder\u00edas (5 escuelas) as\u00ed como del mix de financiaci\u00f3n \u00f3ptimo\u201d<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb header_2_font=\u00bbCatamaran||||||||\u00bb header_3_font=\u00bbCatamaran|900|||||||\u00bb min_height=\u00bb400px\u00bb custom_margin=\u00bb||-4px|||\u00bb custom_padding=\u00bb20px|20px|0px|20px|false|false\u00bb box_shadow_style=\u00bbpreset1&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sendersfinancers.com\/wp-content\/uploads\/2021\/08\/logo-cl-2.png\" width=\"106\" height=\"109\" alt=\"\" class=\"wp-image-3394 alignnone size-full\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\">AYUNTAMIENTO\u00a0DE<\/h2>\n<h3 style=\"text-align: center;\">BLANES<\/h3>\n<div style=\"background: #f2f2f2; padding: 10px; margin: 10px 10px; text-align: center;\">Informe econ\u00f3mico de determinaci\u00f3n del coste objetivo del servicio de guarder\u00edas (3 guarder\u00edas) as\u00ed como del mix de financiaci\u00f3n \u00f3ptimo<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb custom_margin=\u00bb20px||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb header_2_font=\u00bbCatamaran||||||||\u00bb header_3_font=\u00bbCatamaran|900|||||||\u00bb min_height=\u00bb400px\u00bb custom_padding=\u00bb7px|20px|20px|20px|false|false\u00bb box_shadow_style=\u00bbpreset1&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sendersfinancers.com\/wp-content\/uploads\/2023\/12\/castellar-del-valles-300x246.jpg\" width=\"135\" height=\"111\" alt=\"\" class=\"wp-image-5953 alignnone size-medium\" srcset=\"https:\/\/www.sendersfinancers.com\/wp-content\/uploads\/2023\/12\/castellar-del-valles-300x246.jpg 300w, https:\/\/www.sendersfinancers.com\/wp-content\/uploads\/2023\/12\/castellar-del-valles.jpg 468w\" sizes=\"(max-width: 135px) 100vw, 135px\" \/><\/p>\n<p style=\"text-align: center;\">\n<h2 style=\"text-align: center;\">AYUNTAMIENTO<\/h2>\n<h3 style=\"text-align: center;\">DE CASTELLAR DEL VALL\u00c8S<\/h3>\n<div style=\"background: #f2f2f2; padding: 10px; margin: 10px 10px; text-align: center;\">Informe econ\u00f3mico de determinaci\u00f3n del coste objetivo del servicio de jardines de infancia (2 escuelas) as\u00ed como del mix de financiaci\u00f3n \u00f3ptimo<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb header_2_font=\u00bbCatamaran||||||||\u00bb header_3_font=\u00bbCatamaran|900|||||||\u00bb min_height=\u00bb400px\u00bb custom_padding=\u00bb7px|20px|20px|20px|false|false\u00bb box_shadow_style=\u00bbpreset1&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sendersfinancers.com\/wp-content\/uploads\/2023\/02\/SANT-JAUME-DE-LLIERCA-300x300.jpg\" width=\"130\" height=\"130\" alt=\"\" class=\"wp-image-5412 alignnone size-medium\" \/><\/p>\n<h2 style=\"text-align: center;\">AYUNTAMIENTO<\/h2>\n<h3 style=\"text-align: center;\">DE SANT JAUME DE LLIERCA<\/h3>\n<div style=\"background: #f2f2f2; padding: 10px; margin: 10px 10px; text-align: center;\">Informe econ\u00f3mico de determinaci\u00f3n del coste objetivo del servicio de guarder\u00edas as\u00ed como del mix de financiaci\u00f3n \u00f3ptimo<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb header_2_font=\u00bbCatamaran||||||||\u00bb header_3_font=\u00bbCatamaran|900|||||||\u00bb min_height=\u00bb400px\u00bb height=\u00bb400px\u00bb custom_padding=\u00bb20px|20px|20px|20px|false|false\u00bb box_shadow_style=\u00bbpreset1&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sendersfinancers.com\/wp-content\/uploads\/2019\/09\/matadepera-300x118.png\" width=\"300\" height=\"118\" alt=\"\" class=\"wp-image-1166 alignnone size-medium\" style=\"display: block; margin-left: auto; margin-right: auto;\" srcset=\"https:\/\/www.sendersfinancers.com\/wp-content\/uploads\/2019\/09\/matadepera-300x118.png 300w, https:\/\/www.sendersfinancers.com\/wp-content\/uploads\/2019\/09\/matadepera.png 306w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h2 style=\"text-align: center;\"><\/h2>\n<h2 style=\"text-align: center;\">AYUNTAMIENTO\u00a0DE<\/h2>\n<h3 style=\"text-align: center;\">MATADEPERA<\/h3>\n<div style=\"background: #f2f2f2; padding: 10px; margin: 10px 10px; text-align: center;\">Informe econ\u00f3mico de determinaci\u00f3n del coste objetivo del servicio de guarder\u00edas as\u00ed como del mix de financiaci\u00f3n \u00f3ptimo<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb custom_margin=\u00bb20px||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb header_2_font=\u00bbCatamaran||||||||\u00bb header_3_font=\u00bbCatamaran|900|||||||\u00bb min_height=\u00bb400px\u00bb custom_padding=\u00bb20px|20px|20px|20px|false|false\u00bb box_shadow_style=\u00bbpreset1&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sendersfinancers.com\/wp-content\/uploads\/2020\/03\/corca.png\" width=\"260\" height=\"100\" alt=\"\" class=\"wp-image-1702 alignnone size-full\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\">AYUNTAMIENTO\u00a0DE<\/h2>\n<h3 style=\"text-align: center;\">COR\u00c7\u00c0<\/h3>\n<div style=\"background: #f2f2f2; padding: 10px; margin: 10px 10px; text-align: center;\">Informe econ\u00f3mico de determinaci\u00f3n del coste objetivo del servicio de guarder\u00edas as\u00ed como del mix de financiaci\u00f3n \u00f3ptimo<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb header_2_font=\u00bbCatamaran||||||||\u00bb header_3_font=\u00bbCatamaran|900|||||||\u00bb min_height=\u00bb400px\u00bb max_height=\u00bb400px\u00bb custom_padding=\u00bb7px|20px|20px|20px|false|false\u00bb box_shadow_style=\u00bbpreset1&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sendersfinancers.com\/wp-content\/uploads\/2022\/07\/Torello-300x300.jpg\" width=\"137\" height=\"137\" alt=\"\" class=\"wp-image-5121 alignnone size-medium\" srcset=\"https:\/\/www.sendersfinancers.com\/wp-content\/uploads\/2022\/07\/Torello-300x300.jpg 300w, https:\/\/www.sendersfinancers.com\/wp-content\/uploads\/2022\/07\/Torello-150x150.jpg 150w, https:\/\/www.sendersfinancers.com\/wp-content\/uploads\/2022\/07\/Torello.jpg 400w\" sizes=\"(max-width: 137px) 100vw, 137px\" \/><\/p>\n<h2 style=\"text-align: center;\">AYUNTAMIENTO<\/h2>\n<h3 style=\"text-align: center;\">DE TORELL\u00d3<\/h3>\n<div style=\"background: #f2f2f2; padding: 10px; margin: 10px 10px; text-align: center;\"><span>Informe econ\u00f3mico de determinaci\u00f3n del coste objetivo del servicio de jardines de infancia (2 escuelas) as\u00ed como del mix de financiaci\u00f3n \u00f3ptima cuna gesti\u00f3n<\/span><\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb header_2_font=\u00bbCatamaran||||||||\u00bb header_3_font=\u00bbCatamaran|900|||||||\u00bb min_height=\u00bb400px\u00bb custom_padding=\u00bb7px|20px|20px|20px|false|false\u00bb box_shadow_style=\u00bbpreset1&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sendersfinancers.com\/wp-content\/uploads\/2024\/03\/Escut_de_Sant_Esteve_de_Palautordera.svg_-186x300.png\" width=\"90\" height=\"145\" alt=\"\" class=\"wp-image-6045 alignnone size-medium\" \/><\/p>\n<h2 style=\"text-align: center;\">AYUNTAMIENTO<\/h2>\n<h3 style=\"text-align: center;\">DE SANT ESTEVE DE PALAUTORDERA<\/h3>\n<div style=\"background: #f2f2f2; padding: 10px; margin: 10px 10px; texto-align: center;\">Estudio de viabilidad de jardines de infancia y determinaci\u00f3n de la forma de gesti\u00f3n m\u00e1s eficiente entre diferentes modalidades de gesti\u00f3n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb custom_margin=\u00bb20px||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb header_2_font=\u00bbCatamaran||||||||\u00bb header_3_font=\u00bbCatamaran|900|||||||\u00bb min_height=\u00bb400px\u00bb custom_padding=\u00bb7px|20px|20px|20px|false|false\u00bb box_shadow_style=\u00bbpreset1&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sendersfinancers.com\/wp-content\/uploads\/2024\/03\/layout_set_logo.png\" width=\"250\" height=\"103\" alt=\"\" class=\"wp-image-6043 alignnone size-full\" \/><\/p>\n<h2 style=\"text-align: center;\">AYUNTAMIENTO<\/h2>\n<h3 style=\"text-align: center;\">DE VILASSAR DE MAR<\/h3>\n<div style=\"background: #f2f2f2; padding: 10px; margin: 10px 10px; text-align: center;\">Estudios econ\u00f3micos, jur\u00eddicos y laborales para el cambio de modalidad de gesti\u00f3n de las EEBB municipales (2 escuelas) de Organismo Aut\u00f3nomo a gesti\u00f3n directa por parte del Ayuntamiento<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb header_2_font=\u00bbCatamaran||||||||\u00bb header_3_font=\u00bbCatamaran|900|||||||\u00bb height=\u00bb400px\u00bb custom_padding=\u00bb7px|20px|20px|20px|false|false\u00bb hover_enabled=\u00bb0&#8243; box_shadow_style=\u00bbpreset1&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.sendersfinancers.com\/wp-content\/uploads\/2026\/02\/ripollet.png\" width=\"215\" height=\"122\" alt=\"\" class=\"wp-image-6815 alignnone size-full\" \/><\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #333333;\"><\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #333333;\">AYUNTAMIENTO<\/span><\/h2>\n<h3 style=\"text-align: center;\">DE RIPOLLET<\/h3>\n<div style=\"background: #f2f2f2; padding: 10px; margin: 10px 10px; text-align: center;\">\n<p><span style=\"color: #333333;\">Estudios de costes relacionados con el \u00c1rea de Servicios Educativos<\/span><\/p>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbContact Section\u00bb _builder_version=\u00bb4.10.5&#8243; background_color_gradient_direction=\u00bb105deg\u00bb min_height_tablet=\u00bb\u00bb min_height_phone=\u00bb\u00bb min_height_last_edited=\u00bbon|desktop\u00bb custom_padding=\u00bb||0px||false|false\u00bb top_divider_height=\u00bb15px\u00bb border_width_top=\u00bb10px\u00bb border_color_top=\u00bb#569033&#8243; global_module=\u00bb2500&#8243; collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; admin_label=\u00bbContact Area\u00bb module_class=\u00bb et_pb_row_fullwidth\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb width_tablet=\u00bb80%\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|desktop\u00bb max_width_tablet=\u00bb80%\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb module_alignment=\u00bbcenter\u00bb min_height_tablet=\u00bb\u00bb min_height_phone=\u00bb\u00bb min_height_last_edited=\u00bbon|desktop\u00bb custom_margin=\u00bb|0px|40px|0px|false|false\u00bb custom_padding=\u00bb||0px||false|false\u00bb border_color_all=\u00bb#7cda24&#8243; make_fullwidth=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bbCatamaran|900|||||||\u00bb header_2_text_color=\u00bb#569033&#8243; header_2_font_size=\u00bb30px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>CONTACTA<br \/>CON NOSOTROS<\/h2>\n<p>[\/et_pb_text][et_pb_code _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb min_height=\u00bb0px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div class=\"et_pb_row_1\" style=\"min-height:0\"><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"et_pb_column et_pb_column_3_5\" style=\"<!-- [et_pb_line_break_holder] -->    vertical-align: middle;<!-- [et_pb_line_break_holder] -->    line-height: 20px;<!-- [et_pb_line_break_holder] -->\u00ab>  <!-- [et_pb_line_break_holder] -->    <a href=\"tel:646147415\"><img decoding=\"async\" src=\"http:\/\/sendersfinancers.com\/wp-content\/uploads\/2021\/08\/phone-ico.png\"><\/a><!-- [et_pb_line_break_holder] --><a href=\"mailto:andreulopez@sendersfinancers.com\" style=\"<!-- [et_pb_line_break_holder] -->    vertical-align: top;<!-- [et_pb_line_break_holder] -->    line-height: 95px;<!-- [et_pb_line_break_holder] -->    padding-left: 20px;<!-- [et_pb_line_break_holder] -->\t\tcolor:#000000;<!-- [et_pb_line_break_holder] -->\u00ab>646 14 74 15<\/a><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] --><\/div>\n<p><!-- [et_pb_line_break_holder] --><\/p>\n<div class=\"et_pb_row_1\"><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"et_pb_column et_pb_column_5_5\" style=\"<!-- [et_pb_line_break_holder] -->    vertical-align: middle;<!-- [et_pb_line_break_holder] -->    line-height: 20px;<!-- [et_pb_line_break_holder] -->\u00ab>  <!-- [et_pb_line_break_holder] -->    <a href=\"mailto:andreulopez@sendersfinancers.com\"><img decoding=\"async\" src=\"http:\/\/sendersfinancers.com\/wp-content\/uploads\/2021\/08\/phone-email.png\"><\/a><!-- [et_pb_line_break_holder] --><a href=\"mailto:andreulopez@sendersfinancers.com\" style=\"<!-- [et_pb_line_break_holder] -->    vertical-align: top;<!-- [et_pb_line_break_holder] -->    line-height: 95px;<!-- [et_pb_line_break_holder] -->    padding-left: 20px;<!-- [et_pb_line_break_holder] -->\t\tcolor:#000000;<!-- [et_pb_line_break_holder] -->\u00ab>andreulopez@sendersfinancers.com<\/a><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][et_pb_code _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_code][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_code _builder_version=\u00bb4.16&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_direction=\u00bb30deg\u00bb background_color_gradient_stops=\u00bb#569033 10%|#afb81f 100%\u00bb background_color_gradient_start=\u00bb#569033&#8243; background_color_gradient_start_position=\u00bb10%\u00bb background_color_gradient_end=\u00bb#afb81f\u00bb background_image=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2021\/08\/bg-form.png\u00bb parallax=\u00bbon\u00bb parallax_method=\u00bboff\u00bb text_orientation=\u00bbleft\u00bb width=\u00bb100%\u00bb min_height=\u00bb444.5px\u00bb custom_margin=\u00bb||0px||false|false\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb||40px||false|false\u00bb text_orientation_tablet=\u00bb\u00bb text_orientation_phone=\u00bb\u00bb text_orientation_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<pee>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1745-o1\" lang=\"ca\" dir=\"ltr\" data-wpcf7-id=\"1745\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/6525#wpcf7-f1745-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulari de contacte\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1745\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"ca\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1745-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"block-1\">\n\t<div class=\"name-block\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre...\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"surname-block\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"surname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Apellidos...\" value=\"\" type=\"text\" name=\"surname\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"block-2\">\n\t<p><label> <span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail...\" value=\"\" type=\"email\" name=\"email\" \/><\/span> <\/label>\n\t<\/p>\n<\/div>\n<p><span id=\"wpcf7-6a98791c5717e-wrapper\" class=\"wpcf7-form-control-wrap cf7apps-honeypot-wrap website-wrap\" data-cf7apps-honeypot=\"website\" style=\"position:absolute;width:1px;height:1px;padding:0;margin:-1px;overflow:hidden;clip:rect(0,0,0,0);white-space:nowrap;border:0;\"><input type=\"hidden\" name=\"website-random-hash\" value=\"20260902\"><input type=\"hidden\" name=\"website-time-token\" value=\"MTc4ODM3NzM3Mg==.ef2d9984db348cc74728f958874219704b248677b7ea695513743674f32ba23d\"><label\n\t\t    for=\"wpcf7-6a98791c5717e-field\"\n\t\t    class=\"hp-message\"\n        >Deixeu aquest camp buit.<\/label><input\n\t    id=\"wpcf7-6a98791c5717e-field\"\n\t    \n\t    class=\"wpcf7-form-control wpcf7-text\"\n\t    type=\"text\"\n\t    name=\"zgzmzxvritcr\"\n\t    value=\"\"\n\t    autocomplete=\"new-password\"\n\t    tabindex=\"1000\"\n\t    data-cf7apps-tabindex=\"1000\"\n    \/><\/span>\n<\/p>\n<div class=\"block-3\">\n\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Cu\u00e9ntanos tu caso...\" name=\"message\"><\/textarea><\/span><\/label>\n\t<\/p>\n<\/div>\n<div class=\"block-footer\">\n\t<div class=\"left-col\">\n\t\t<div>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-newsletter\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-newsletter\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span> Quiero recibir novedades y noticias de Senders Financers\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-politica\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-politica\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span> He le\u00eddo y acepto la <a href=\"\/politica-de-privacidad\" target=\"_blank\">pol\u00edtica de privacidad<\/a>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"right-col\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"123\"\/><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n\/* ]]> *\/\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/pee>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbBest Beans\u00bb _builder_version=\u00bb4.16&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_direction=\u00bb81deg\u00bb background_color_gradient_stops=\u00bb#569033 0%|#b6bc1d 100%\u00bb background_color_gradient_start=\u00bb#569033&#8243; background_color_gradient_end=\u00bb#b6bc1d\u00bb custom_padding=\u00bb30px|0px|60px|0px|false|false\u00bb collapsed=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||20px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bbCatamaran|900|||||||\u00bb header_2_text_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: center;\">\u00bfC\u00d3MO TRABAJAMOS?<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2021\/08\/integral-h.png\u00bb title_text=\u00bbintegral-h\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb header_font=\u00bbCatamaran|900|||||||\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_2_font=\u00bbCatamaran|900|||||||\u00bb header_2_text_color=\u00bb#FFFFFF\u00bb header_2_font_size=\u00bb30px\u00bb min_height=\u00bb69.2px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: center;\">AN\u00c1LISIS INTEGRAL<br \/>DE LA SITUACI\u00d3N<\/h2>\n<p style=\"text-align: center;\">Analizamos el pasado, el presente y el futuro de tus finanzas para conseguir la mejor comprensi\u00f3n y diagn\u00f3stico de la situaci\u00f3n actual planteada.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2021\/08\/integral-h3.png\u00bb title_text=\u00bbintegral-h3&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb header_font=\u00bbCatamaran|900|||||||\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_2_font=\u00bbCatamaran|900|||||||\u00bb header_2_text_color=\u00bb#FFFFFF\u00bb header_2_font_size=\u00bb30px\u00bb min_height=\u00bb69.2px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: center;\">VISI\u00d3N Y PERSPECTIVA SIMPLIFICADA<\/h2>\n<p style=\"text-align: center;\">Simplificamos entornos econ\u00f3micos complejos en que el exceso de los flujos de informaci\u00f3n nos distorsiona la interpretaci\u00f3n y los convertimos en estudios y an\u00e1lisis que proporcionan una visi\u00f3n y perspectiva simplificada.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2021\/08\/integral-h2.png\u00bb title_text=\u00bbintegral-h2&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb header_font=\u00bbCatamaran|900|||||||\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_2_font=\u00bbCatamaran|900|||||||\u00bb header_2_text_color=\u00bb#FFFFFF\u00bb header_2_font_size=\u00bb30px\u00bb min_height=\u00bb69.2px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: center;\">FACILITACI\u00d3N EN LA TOMA DE DECISIONES<\/h2>\n<p style=\"text-align: center;\">No tomamos decisiones por ti, ya que te facilitamos el m\u00e1ximo la toma de decisiones y te damos soporte profesional en todo momento.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.13.1&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb40px||||false|false\u00bb custom_padding=\u00bb10px||||false|false\u00bb border_width_top=\u00bb8px\u00bb border_color_top=\u00bb#569033&#8243; global_module=\u00bb3755&#8243; saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbCatamaran|900|||||||\u00bb header_text_color=\u00bb#569033&#8243; header_2_font=\u00bbCatamaran|900|||||||\u00bb header_2_text_color=\u00bb#569033&#8243; header_2_font_size=\u00bb30px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: center;\">\u00bfPOR QU\u00c9 ELEGIRNOS?<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb40px||||false|false\u00bb custom_padding=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|40px|20px|false|false\u00bb box_shadow_style=\u00bbpreset1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2021\/08\/ico-1.png\u00bb title_text=\u00bbico-1&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; header_font=\u00bbCatamaran|900|||||||\u00bb header_2_font=\u00bbCatamaran|900|||||||\u00bb header_2_text_color=\u00bb#000000&#8243; header_2_font_size=\u00bb30px\u00bb custom_padding=\u00bb||12px|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: center;\">RIGOR<br \/>PROFESIONAL<\/h2>\n<p style=\"text-align: center;\">Buscamos la excelencia en el desarrollo de nuestra tarea profesional y perseguimos aportar soluciones con los m\u00e1ximos niveles de calidad.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|65px|20px|false|false\u00bb box_shadow_style=\u00bbpreset1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2021\/08\/ico-2.png\u00bb title_text=\u00bbico-2&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; header_font=\u00bbCatamaran|900|||||||\u00bb header_2_font=\u00bbCatamaran|900|||||||\u00bb header_2_font_size=\u00bb30px\u00bb custom_margin=\u00bb||-2px|||\u00bb custom_padding=\u00bb||18px|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: center;\">ESPECIALIZACI\u00d3N<\/h2>\n<p style=\"text-align: center;\">Nuestro equipo de profesionales presenta elevados conocimientos en los campos de la consultor\u00eda financiera y derecho administrativo y apuesta por la formaci\u00f3n y mejora continua.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|40px|20px|false|false\u00bb box_shadow_style=\u00bbpreset1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2021\/08\/ico-3-1.png\u00bb title_text=\u00bbico-3&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; header_font=\u00bbCatamaran|900|||||||\u00bb header_2_font=\u00bbCatamaran|900|||||||\u00bb header_2_font_size=\u00bb30px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: center;\">ORIENTACI\u00d3N<br \/>AL CLIENTE<\/h2>\n<p style=\"text-align: center;\">Ponemos al cliente en el centro para identificar las necesidades y prioridades que le surjan y buscando siempre la mejor soluci\u00f3n para satisfacer sus necesidades.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb40px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|40px|20px|false|false\u00bb box_shadow_style=\u00bbpreset1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2021\/08\/ico-4-1.png\u00bb title_text=\u00bbico-4&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; header_font=\u00bbCatamaran|900|||||||\u00bb header_2_font=\u00bbCatamaran|900|||||||\u00bb header_2_font_size=\u00bb30px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: center;\">RESOLUCI\u00d3N DE PROBLEMAS<\/h2>\n<p style=\"text-align: center;\">Presentamos una alta capacidad para obtener soluciones a las diferentes situaciones e incidencias econ\u00f3micas que nos plantean nuestros clientes.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|40px|20px|false|false\u00bb box_shadow_style=\u00bbpreset1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2021\/09\/email.png\u00bb title_text=\u00bbemail\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; header_font=\u00bbCatamaran|900|||||||\u00bb header_2_font=\u00bbCatamaran|900|||||||\u00bb header_2_font_size=\u00bb30px\u00bb custom_margin=\u00bb||12px|||\u00bb custom_padding=\u00bb||52px|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: center;\">COMUNICACI\u00d3N<\/h2>\n<p style=\"text-align: center;\">Somos comunicativos y te mantendremos en todo momento informado del grado de avance de la tarea que nos hayas encomendado.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|20px|40px|20px|false|false\u00bb box_shadow_style=\u00bbpreset1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2021\/08\/ico-5.png\u00bb title_text=\u00bbico-5&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbCatamaran||||||||\u00bb text_text_color=\u00bb#000101&#8243; header_font=\u00bbCatamaran|900|||||||\u00bb header_2_font=\u00bbCatamaran|900|||||||\u00bb header_2_font_size=\u00bb29px\u00bb min_height=\u00bb160.8px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: center;\">RESPONSABILIDAD SOCIAL<\/h2>\n<p style=\"text-align: center;\">Procuramos causar un impacto amplio y positivo en la comunidad con acciones corporativas que promuevan la Solidaridad.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb60px||40px||false|false\u00bb custom_padding=\u00bb10px||10px||false|false\u00bb border_width_top=\u00bb8px\u00bb border_color_top=\u00bb#569033&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbCatamaran|900|||||||\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#569033&#8243; header_2_font_size=\u00bb16px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>ALGUNOS DE NUESTROS CLIENTES<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb40px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2023\/07\/generalitat2.png\u00bb alt=\u00bbajuntament del vendrell\u00bb title_text=\u00bbgeneralitat2&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb65%\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2022\/04\/1..jpg\u00bb alt=\u00bbajuntament del vendrell\u00bb title_text=\u00bb1.\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2023\/06\/Logo_Ajuntament_Sabadell.jpg\u00bb alt=\u00bbajuntament del vendrell\u00bb title_text=\u00bbLogo_Ajuntament_Sabadell\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb custom_margin=\u00bb20px||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2019\/11\/Caldes-de-Montbui.png\u00bb alt=\u00bbajuntament del vendrell\u00bb title_text=\u00bbCaldes de Montbui\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb40px||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2022\/04\/Imagen1.png\u00bb alt=\u00bbajuntament del vendrell\u00bb title_text=\u00bbImagen1&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb85%\u00bb custom_margin=\u00bb30px||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2024\/02\/nerja2.jpg\u00bb alt=\u00bbajuntament del vendrell\u00bb title_text=\u00bbnerja2&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb70%\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2019\/09\/auria.jpg\u00bb alt=\u00bbajuntament del vendrell\u00bb title_text=\u00bbauria\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb70%\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2022\/12\/1.png\u00bb alt=\u00bbajuntament del vendrell\u00bb title_text=\u00bb1&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb20px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb40px||40px||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2024\/06\/figueres.png\u00bb alt=\u00bbajuntament del vendrell\u00bb title_text=\u00bbfigueres\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb custom_margin=\u00bb10px||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2024\/10\/logo-ajuntament-amposta-horitzontal-dos-linies.png\u00bb alt=\u00bbajuntament del vendrell\u00bb title_text=\u00bblogo-ajuntament-amposta-horitzontal-dos-linies\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb custom_margin=\u00bb9px||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2019\/09\/matadepera.png\u00bb alt=\u00bbajuntament del vendrell\u00bb title_text=\u00bbmatadepera\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/sendersfinancers.com\/wp-content\/uploads\/2023\/10\/logo-cmdp.png\u00bb alt=\u00bbajuntament del vendrell\u00bb title_text=\u00bblogo-cmdp\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb20px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GUARDER\u00cdASSERVICIO DE ESTUDIOS DE ESTRUCTURA DE COSTES DE GUARDER\u00cdAS SERVICIOS DE CONSULTOR\u00cdA FINANCIERA PARA AYUNTAMIENTOSLa Ley 5\/2004, de 9 de julio, de creaci\u00f3n de guarder\u00edas de calidad, estableci\u00f3 que el Gobierno de Catalu\u00f1a deb\u00eda garantizar el car\u00e1cter educativo, la calidad y los requisitos m\u00ednimos que deben cumplir las guarder\u00edas que la realidad catalana exige, y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6528,"parent":3881,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-6525","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u1405 Guarder\u00edas | Estudio Estructura Costes | SENDERS FINANCERS<\/title>\n<meta name=\"description\" content=\"Servicio de Estudio de Estructura de Costes de Guarder\u00edas para Ayuntamientos. \u00a1Ponte en contacto con nosotros ahora!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sendersfinancers.com\/es\/ayuntamientos\/estudios-de-estructura-de-gastos\/guarderias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u1405 Guarder\u00edas | Estudio Estructura Costes | SENDERS FINANCERS\" \/>\n<meta property=\"og:description\" content=\"Servicio de Estudio de Estructura de Costes de Guarder\u00edas para Ayuntamientos. \u00a1Ponte en contacto con nosotros ahora!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sendersfinancers.com\/es\/ayuntamientos\/estudios-de-estructura-de-gastos\/guarderias\/\" \/>\n<meta property=\"og:site_name\" content=\"Senders Financers\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-26T08:57:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sendersfinancers.com\/wp-content\/uploads\/2025\/10\/Banner-PAGE-2-1024x468.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"468\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sendersfinancers.com\\\/es\\\/ayuntamientos\\\/estudios-de-estructura-de-gastos\\\/guarderias\\\/\",\"url\":\"https:\\\/\\\/www.sendersfinancers.com\\\/es\\\/ayuntamientos\\\/estudios-de-estructura-de-gastos\\\/guarderias\\\/\",\"name\":\"\u1405 Guarder\u00edas | Estudio Estructura Costes | SENDERS FINANCERS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sendersfinancers.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sendersfinancers.com\\\/es\\\/ayuntamientos\\\/estudios-de-estructura-de-gastos\\\/guarderias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sendersfinancers.com\\\/es\\\/ayuntamientos\\\/estudios-de-estructura-de-gastos\\\/guarderias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sendersfinancers.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Banner-PAGE-2.png\",\"datePublished\":\"2025-10-06T14:24:43+00:00\",\"dateModified\":\"2026-02-26T08:57:40+00:00\",\"description\":\"Servicio de Estudio de Estructura de Costes de Guarder\u00edas para Ayuntamientos. \u00a1Ponte en contacto con nosotros ahora!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sendersfinancers.com\\\/es\\\/ayuntamientos\\\/estudios-de-estructura-de-gastos\\\/guarderias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sendersfinancers.com\\\/es\\\/ayuntamientos\\\/estudios-de-estructura-de-gastos\\\/guarderias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sendersfinancers.com\\\/es\\\/ayuntamientos\\\/estudios-de-estructura-de-gastos\\\/guarderias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sendersfinancers.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Banner-PAGE-2.png\",\"contentUrl\":\"https:\\\/\\\/www.sendersfinancers.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Banner-PAGE-2.png\",\"width\":1920,\"height\":878},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sendersfinancers.com\\\/es\\\/ayuntamientos\\\/estudios-de-estructura-de-gastos\\\/guarderias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.sendersfinancers.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ayuntamientos\",\"item\":\"https:\\\/\\\/www.sendersfinancers.com\\\/es\\\/ayuntamientos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Estudios de estructura de gastos\",\"item\":\"https:\\\/\\\/www.sendersfinancers.com\\\/es\\\/ajuntaments\\\/estudis-destructura-de-costos\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Guarder\u00edas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sendersfinancers.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.sendersfinancers.com\\\/es\\\/\",\"name\":\"Senders Financers\",\"description\":\"Altre lloc gestionat amb el WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sendersfinancers.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u1405 Guarder\u00edas | Estudio Estructura Costes | SENDERS FINANCERS","description":"Servicio de Estudio de Estructura de Costes de Guarder\u00edas para Ayuntamientos. \u00a1Ponte en contacto con nosotros ahora!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sendersfinancers.com\/es\/ayuntamientos\/estudios-de-estructura-de-gastos\/guarderias\/","og_locale":"es_ES","og_type":"article","og_title":"\u1405 Guarder\u00edas | Estudio Estructura Costes | SENDERS FINANCERS","og_description":"Servicio de Estudio de Estructura de Costes de Guarder\u00edas para Ayuntamientos. \u00a1Ponte en contacto con nosotros ahora!","og_url":"https:\/\/www.sendersfinancers.com\/es\/ayuntamientos\/estudios-de-estructura-de-gastos\/guarderias\/","og_site_name":"Senders Financers","article_modified_time":"2026-02-26T08:57:40+00:00","og_image":[{"width":1024,"height":468,"url":"https:\/\/www.sendersfinancers.com\/wp-content\/uploads\/2025\/10\/Banner-PAGE-2-1024x468.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sendersfinancers.com\/es\/ayuntamientos\/estudios-de-estructura-de-gastos\/guarderias\/","url":"https:\/\/www.sendersfinancers.com\/es\/ayuntamientos\/estudios-de-estructura-de-gastos\/guarderias\/","name":"\u1405 Guarder\u00edas | Estudio Estructura Costes | SENDERS FINANCERS","isPartOf":{"@id":"https:\/\/www.sendersfinancers.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sendersfinancers.com\/es\/ayuntamientos\/estudios-de-estructura-de-gastos\/guarderias\/#primaryimage"},"image":{"@id":"https:\/\/www.sendersfinancers.com\/es\/ayuntamientos\/estudios-de-estructura-de-gastos\/guarderias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sendersfinancers.com\/wp-content\/uploads\/2025\/10\/Banner-PAGE-2.png","datePublished":"2025-10-06T14:24:43+00:00","dateModified":"2026-02-26T08:57:40+00:00","description":"Servicio de Estudio de Estructura de Costes de Guarder\u00edas para Ayuntamientos. \u00a1Ponte en contacto con nosotros ahora!","breadcrumb":{"@id":"https:\/\/www.sendersfinancers.com\/es\/ayuntamientos\/estudios-de-estructura-de-gastos\/guarderias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sendersfinancers.com\/es\/ayuntamientos\/estudios-de-estructura-de-gastos\/guarderias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sendersfinancers.com\/es\/ayuntamientos\/estudios-de-estructura-de-gastos\/guarderias\/#primaryimage","url":"https:\/\/www.sendersfinancers.com\/wp-content\/uploads\/2025\/10\/Banner-PAGE-2.png","contentUrl":"https:\/\/www.sendersfinancers.com\/wp-content\/uploads\/2025\/10\/Banner-PAGE-2.png","width":1920,"height":878},{"@type":"BreadcrumbList","@id":"https:\/\/www.sendersfinancers.com\/es\/ayuntamientos\/estudios-de-estructura-de-gastos\/guarderias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.sendersfinancers.com\/es\/"},{"@type":"ListItem","position":2,"name":"Ayuntamientos","item":"https:\/\/www.sendersfinancers.com\/es\/ayuntamientos\/"},{"@type":"ListItem","position":3,"name":"Estudios de estructura de gastos","item":"https:\/\/www.sendersfinancers.com\/es\/ajuntaments\/estudis-destructura-de-costos\/"},{"@type":"ListItem","position":4,"name":"Guarder\u00edas"}]},{"@type":"WebSite","@id":"https:\/\/www.sendersfinancers.com\/es\/#website","url":"https:\/\/www.sendersfinancers.com\/es\/","name":"Senders Financers","description":"Altre lloc gestionat amb el WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sendersfinancers.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.sendersfinancers.com\/es\/wp-json\/wp\/v2\/pages\/6525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sendersfinancers.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sendersfinancers.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sendersfinancers.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sendersfinancers.com\/es\/wp-json\/wp\/v2\/comments?post=6525"}],"version-history":[{"count":10,"href":"https:\/\/www.sendersfinancers.com\/es\/wp-json\/wp\/v2\/pages\/6525\/revisions"}],"predecessor-version":[{"id":6820,"href":"https:\/\/www.sendersfinancers.com\/es\/wp-json\/wp\/v2\/pages\/6525\/revisions\/6820"}],"up":[{"embeddable":true,"href":"https:\/\/www.sendersfinancers.com\/es\/wp-json\/wp\/v2\/pages\/3881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sendersfinancers.com\/es\/wp-json\/wp\/v2\/media\/6528"}],"wp:attachment":[{"href":"https:\/\/www.sendersfinancers.com\/es\/wp-json\/wp\/v2\/media?parent=6525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}